{"id":680586,"date":"2021-10-20T14:53:53","date_gmt":"2021-10-20T06:53:53","guid":{"rendered":"https:\/\/www.cool-style.com.tw\/wd2\/?p=680586"},"modified":"2021-10-20T19:13:58","modified_gmt":"2021-10-20T11:13:58","slug":"%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c","status":"publish","type":"post","link":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c","title":{"rendered":"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01"},"content":{"rendered":"\n<p>\u4e0a\u56de\u6211\u5011\u624d\u5728\uff1a\u300c<a href=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/677991\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/677991\">\u7d30\u7bc0\u4e0d\u8f38\u806f\u540d\u6b3e\uff01\u5168\u65b0 Nike Air Force 1 \u8b8a\u5f62\u87f2\u914d\u8272\u91cb\u51fa\uff0c\u7c21\u7d04\u8cea\u611f\u6709\u5920\u71d2\uff01<\/a>\u300d\u4e2d\uff0c\u70ba\u5927\u5bb6\u5e36\u4f86\u4e86\u4e00\u6b3e\u904b\u7528\u8b8a\u5f62\u87f2\u5143\u7d20\u4ee5\u53ca\u6c34\u85cd\u8272\u8abf\u7684\u5168\u65b0 Nike Air Force 1\uff0c\u6f6e\u6d41\u611f\u5341\u8db3\u7684\u8a2d\u8a08\u52a0\u4e0a\u4ee5\u7d14\u767d Air Force 1 \u70ba\u8f09\u9ad4\u7684\u767e\u642d\u7279\u9ede\uff0c\u8b93\u9019\u96d9\u978b\u7acb\u523b\u5c31\u5438\u5f15\u4f4f\u5927\u5bb6\u7684\u76ee\u5149\u3002<\/p>\n\n\n\n<p>\u7136\u800c\u6b64\u6b3e\u85cd\u8b8a\u5f62\u87f2\u56e0\u70ba\u662f\u5973\u751f\u5c3a\u5bf8\uff0c\u4f7f\u5f97\u8a31\u591a\u7537\u6027\u978b\u8ff7\u5011\u6709\u4e9b\u5931\u671b\uff0c\u53ef\u80fd\u7121\u7de3\u4e0a\u8173\u9019\u96d9\u5ab2\u7f8e\u806f\u540d\u6b3e\u7684\u8a71\u984c\u7403\u978b\u3002\u5e78\u597d\uff0c\u4eca\u65e5\u7db2\u8def\u4e0a\u53c8\u518d\u5ea6\u91cb\u51fa\u4e00\u6b3e\u76f8\u540c\u8a2d\u8a08\u7684\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\uff0c\u5728\u9ed1\u9b42 Swoosh \u7684\u896f\u6258\u4e0b\uff0c\u66f4\u986f\u5f97\u8b8a\u5f62\u87f2\u5716\u9a30\u90a3\u6e3e\u8eab\u6563\u767c\u7684\u6f6e\u6d41\u6c1b\u570d\uff0c\u5c0d\u6bd4\u7684\u9ed1\u767d\u8272\uff0c\u4e5f\u8b93\u6574\u9ad4\u770b\u4f86\u7c21\u7d04\u53c8\u5e25\u6c23\uff0c\u4e14\u91cd\u9ede\u9019\u6b3e\u662f\u7537\u78bc\u5c3a\u5bf8\uff0c\u76f8\u4fe1\u5404\u4f4d\u7537\u7c89\u7d72\u5011\u80af\u5b9a\u53c8\u71c3\u8d77\u5e0c\u671b\uff0c\u5c46\u6642\u8ca9\u552e\u52d9\u5fc5\u8981\u624b\u5200\u5165\u624b\u3002<\/p>\n\n\n\n<script type=\"text\/javascript\">\njQuery( document ).ready(function() {\n\tjQuery( '#example3_680768' ).sliderPro({\n\t\t\/\/width\n\t\t\t\twidth: 1000,\n\t\t\t\t\n\t\t\/\/height\n\t\t\t\theight: 700,\n\t\t\t\t\n\t\t\/\/autoplay\n\t\t\t\tautoplay: true,\n\t\tautoplayOnHover: 'none',\n\t\t\t\t\t\t\t\tautoplayDelay: 5000,\n\t\t\n\t\t\n\t\tarrows: true,\n\t\tbuttons: true,\n\t\tsmallSize: 500,\n\t\tmediumSize: 1000,\n\t\tlargeSize: 3000,\n\t\tfade: true,\n\t\t\n\t\t\/\/thumbnail\n\t\tthumbnailArrows: true,\n\t\tthumbnailWidth: 100,\n\t\tthumbnailHeight: 100,\n\t\t\t\t\t\tthumbnailsPosition: 'bottom',\n\t\t\t\t\t\tcenterImage: true,\n\t\timageScaleMode: 'cover',\n\t\tallowScaleUp: true,\n\t\t\t\tstartSlide: 0,\n\t\tloop: true,\n\t\tslideDistance: 5,\n\t\tautoplayDirection: 'normal',\n\t\ttouchSwipe: true,\n\t\tfullScreen: true,\n\t});\n});\n<\/script>\n<style>\n\/* Layout 3 *\/\n\/* border *\/\n#example3_680768 .sp-selected-thumbnail {\n\tborder: 4px solid #000000;\n}\n\n\/* font + color *\/\n.title-in  {\n\tfont-family: Arial !important;\n\tcolor: #00000 !important;\n\tbackground-color: #FFFFFF !important;\n\topacity: 0.7 !important;\n}\n.desc-in  {\n\tfont-family: Arial !important;\n\tcolor: #FFFFFF !important;\n\tbackground-color: #00000 !important;\n\topacity: 0.7 !important;\n}\n\n\/* bullets color *\/\n.sp-button  {\n\tborder: 2px solid #000000 !important;\n}\n.sp-selected-button  {\n\tbackground-color: #000000 !important;\n}\n\n\/* pointer color - bottom *\/\n.sp-selected-thumbnail::before {\n\tborder-bottom: 5px solid #000000 !important;\n}\n.sp-selected-thumbnail::after {\n\tborder-bottom: 13px solid #000000 !important;\n}\n\n\/* pointer color - top *\/\n\n\/* full screen icon *\/\n.sp-full-screen-button::before {\n    color: #FFFFFF !important;\n}\n\n\/* hover navigation icon color *\/\n.sp-next-arrow::after, .sp-next-arrow::before {\n\tbackground-color: #FFFFFF !important;\n}\n.sp-previous-arrow::after, .sp-previous-arrow::before {\n\tbackground-color: #FFFFFF !important;\n}\n\n#example3_680768 .title-in {\n\tcolor: #00000 !important;\n\tfont-weight: bolder;\n\ttext-align: center;\n}\n\n#example3_680768 .title-in-bg {\n\tbackground: rgba(255, 255, 255, 0.7); !important;\n\twhite-space: unset !important;\n\tmax-width: 90%;\n\tmin-width: 40%;\n\ttransform: initial !important;\n\t-webkit-transform: initial !important;\n\tfont-size: 14px !important;\n}\n\n#example3_680768 .desc-in {\n\tcolor: #FFFFFF !important;\n\ttext-align: center;\n}\n#example3_680768 .desc-in-bg {\n\tbackground: rgba(#00000, 0.7) !important;\n\twhite-space: unset !important;\n\twidth: 80% !important;\n\tmin-width: 30%;\n\ttransform: initial !important;\n\t-webkit-transform: initial !important;\n\tfont-size: 13px !important;\n}\n\n.uris-title{\n\tfont-family: Arial;\n}\n\n@media (max-width: 640px) {\n\t#example3_680768 .hide-small-screen {\n\t\tdisplay: none;\n\t}\n}\n\n@media (max-width: 860px) {\n\t#example3_680768 .sp-layer {\n\t\tfont-size: 18px;\n\t}\n\t\n\t#example3_680768 .hide-medium-screen {\n\t\tdisplay: none;\n\t}\n}\n.fnf{\n\tbackground-color: #a92929;\n\tborder-radius: 5px;\n\tcolor: #fff;\n\tfont-family: initial;\n\ttext-align: center;\n\tpadding:12px;\n}\n\/* Custom CSS *\/\n<\/style>\n<h3 class=\"uris-slider-title uris-title\">Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2<\/h3>\n\t\t<div id=\"example3_680768\" class=\"slider-pro\">\n\t\t\t<!---- slides div start ---->\n\t\t\t<div class=\"sp-slides\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-Release-Date-Price.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-2.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-3.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-5.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-6.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-7.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"sp-slide\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-image\" alt=\"Nike Air Force 1 \u9ed1\u8b8a\u5f62\u87f2\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/css\/images\/blank.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-1.jpeg\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" width=\"560\" height=\"700\" \/>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<!---- slides div end ---->\n\t\t\t\t\t\t<!-- slides thumbnails div start -->\n\t\t\t<div class=\"sp-thumbnails\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-Release-Date-Price.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-2.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-3.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-5.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-6.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-7.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"sp-thumbnail\" src=\"https:\/\/www.cool-style.com.tw\/wd2\/wp-content\/plugins\/ultimate-responsive-image-slider\/img\/loading.gif\" data-src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/Nike-Air-Force-1-Low-Black-Paisley-DH4406-101-Release-Date-1.jpeg\" width=\"100\" height=\"125\" alt=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01\" \/>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<!-- slides thumbnails div end -->\t\n\t\t<\/div>\n\n\n\n\n<p class=\"has-text-align-right\"><em>image via sneakerbardetroit<\/em><\/p>\n\n\n\n<p>Nike Air Force 1 Low \u85cd\u8b8a\u5f62\u87f2\u8207\u9ed1\u8b8a\u5f62\u87f2\u7686\u5c1a\u672a\u91cb\u51fa\u767c\u552e\u65e5\u671f\uff0c\u64da\u6089\u5c07\u65bc 2021 \u5e74\u6b63\u5f0f\u767b\u5834\uff0c\u9084\u8acb\u6709\u8208\u8da3\u7684\u670b\u53cb\u7e7c\u7e8c\u9396\u5b9a COOL \u7684\u8ffd\u8e64\u5831\u5c0e\u3002<\/p>\n\n\n\n<p><strong>\u5ef6\u4f38\u95b1\u8b80\uff1a<a href=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/641754\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/641754\">\u5168\u7403\u9650\u91cf 8000 \u96d9\uff01Air Jordan 1 High OG \u201cRebellionaire\u201d\u5be6\u978b\u7167\u6b63\u5f0f\u66dd\u5149\uff0c\u91cd\u78c5\u7a0b\u5ea6\u76f4\u903c\u806f\u540d\uff01<\/a><\/strong><\/p>\n<div id=\"ad_article_1\" class=\"cool_adgeek_img ad_728x90\" style=\"margin: 10px; text-align: center;\"><\/div>\n\n\n\n<p><strong>\u5ef6\u4f38\u95b1\u8b80\uff1a<a href=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680598\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680598\">\u9084\u662f\u6c92\u958b\u80e1\uff01\u8a79\u7687\u3001AD \u5408\u780d 60+ \u96e3\u6575\u5496\u54e9\u5927\u4e09\u5143\uff0c\u52c7\u58eb\u958b\u5e55\u6230\u672b\u7bc0\u9006\u8f49\u6e56\u4eba\uff01<\/a><\/strong><\/p>\n\n\n\n<p><strong>\u5ef6\u4f38\u95b1\u8b80\uff1a<a href=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/679632\" target=\"_blank\" rel=\"noreferrer noopener\">\u5012\u52fe\u5c31\u662f\u9999\uff01Travis Scott \u66dd\u5149 Air Jordan 1 Low \u806f\u540d\u5168\u65b0\u914d\u8272\uff0c\u9019\u96d9\u7d55\u5c0d\u6436\u7206\uff01<\/a><\/strong><\/p>\n\n\n\n<p><strong>\u5ef6\u4f38\u95b1\u8b80\uff1a<a href=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/679954\" target=\"_blank\" rel=\"noreferrer noopener\">\u300c\u4eba\u9593\u9999\u5948\u5152\u300d\u600e\u9ebc\u7a7f\u90fd\u597d\u770b\uff01BLACKPINK Jennie \u4e0a\u8173 adidas Originals 2021 \u5fa9\u53e4\u7403\u978b\u7cfb\u5217\uff0c\u6027\u611f\u3001\u53ef\u611b\u540c\u6642\u517c\u5177\uff01<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u4e0a\u56de\u6211\u5011\u624d\u5728\uff1a\u300c\u7d30\u7bc0\u4e0d\u8f38\u806f\u540d\u6b3e\uff01\u5168\u65b0 Nike Air Force 1 \u8b8a\u5f62\u87f2\u914d\u8272\u91cb\u51fa\uff0c\u7c21\u7d04\u8cea\u611f\u6709\u5920\u71d2\uff01\u300d\u4e2d\uff0c [&hellip;]<\/p>\n","protected":false},"author":84,"featured_media":680767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[20379,38431],"tags":[38266,38285,1088,414,5010,33224,33157],"class_list":{"0":"post-680586","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-linetodaytrend","8":"category-38431","9":"tag-2021-","11":"tag-air-force-1","12":"tag-nike","13":"tag-nike-air-force-1","14":"tag-nike-","15":"tag-33157"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0-nike-air-force-1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2\" \/>\n<meta property=\"og:description\" content=\"\u4e0a\u56de\u6211\u5011\u624d\u5728\uff1a\u300c\u7d30\u7bc0\u4e0d\u8f38\u806f\u540d\u6b3e\uff01\u5168\u65b0 Nike Air Force 1 \u8b8a\u5f62\u87f2\u914d\u8272\u91cb\u51fa\uff0c\u7c21\u7d04\u8cea\u611f\u6709\u5920\u71d2\uff01\u300d\u4e2d\uff0c [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0-nike-air-force-1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\" \/>\n<meta property=\"og:site_name\" content=\"COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cool.streetfashion\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-20T06:53:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-20T11:13:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/4155.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0-nike-air-force-1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c","og_locale":"zh_TW","og_type":"article","og_title":"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","og_description":"\u4e0a\u56de\u6211\u5011\u624d\u5728\uff1a\u300c\u7d30\u7bc0\u4e0d\u8f38\u806f\u540d\u6b3e\uff01\u5168\u65b0 Nike Air Force 1 \u8b8a\u5f62\u87f2\u914d\u8272\u91cb\u51fa\uff0c\u7c21\u7d04\u8cea\u611f\u6709\u5920\u71d2\uff01\u300d\u4e2d\uff0c [&hellip;]","og_url":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0-nike-air-force-1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c","og_site_name":"COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","article_publisher":"https:\/\/www.facebook.com\/cool.streetfashion\/","article_published_time":"2021-10-20T06:53:53+00:00","article_modified_time":"2021-10-20T11:13:58+00:00","og_image":[{"url":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/4155.jpg","width":1200,"height":628,"type":"image\/jpeg"}],"author":"Arthur","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Arthur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c","url":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c","name":"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","isPartOf":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c#primaryimage"},"image":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c#primaryimage"},"thumbnailUrl":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/4155.jpg","datePublished":"2021-10-20T06:53:53+00:00","dateModified":"2021-10-20T11:13:58+00:00","author":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/#\/schema\/person\/ba61697c4d0d17797fea512c8bb87b19"},"breadcrumb":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c#primaryimage","url":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/4155.jpg","contentUrl":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/10\/4155.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/680586-%e6%af%94%e8%97%8d%e8%89%b2%e6%9b%b4%e5%a5%bd%e7%9c%8b%ef%bc%9f%e5%85%a8%e6%96%b0-nike-air-force-1%e3%80%8c%e9%bb%91%e8%ae%8a%e5%bd%a2%e8%9f%b2%e3%80%8d%e9%87%8d%e7%a3%85%e7%99%bb%e5%a0%b4%ef%bc%8c#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.cool-style.com.tw\/wd2\/"},{"@type":"ListItem","position":2,"name":"\u9177\u978b","item":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/category\/%e7%90%83%e9%9e%8b"},{"@type":"ListItem","position":3,"name":"\u6bd4\u85cd\u8272\u66f4\u597d\u770b\uff1f\u5168\u65b0 Nike Air Force 1\u300c\u9ed1\u8b8a\u5f62\u87f2\u300d\u91cd\u78c5\u767b\u5834\uff0c\u7d30\u7bc0\u7f8e\u5230\u4e0d\u8f38\u806f\u540d\uff01"}]},{"@type":"WebSite","@id":"https:\/\/www.cool-style.com.tw\/wd2\/#website","url":"https:\/\/www.cool-style.com.tw\/wd2\/","name":"COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","description":"\u83ef\u6587\u6f6e\u6d41\u7b2c\u4e00\u54c1\u724c","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cool-style.com.tw\/wd2\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-TW"},{"@type":"Person","@id":"https:\/\/www.cool-style.com.tw\/wd2\/#\/schema\/person\/ba61697c4d0d17797fea512c8bb87b19","name":"Arthur","image":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/www.cool-style.com.tw\/wd2\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d7338d6f3ace14b11598ceabf8191ebf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d7338d6f3ace14b11598ceabf8191ebf?s=96&d=mm&r=g","caption":"Arthur"},"sameAs":["https:\/\/www.instagram.com\/arthurkung725\/"],"url":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/author\/71140"}]}},"_links":{"self":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts\/680586"}],"collection":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/users\/84"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/comments?post=680586"}],"version-history":[{"count":5,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts\/680586\/revisions"}],"predecessor-version":[{"id":680808,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts\/680586\/revisions\/680808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/media\/680767"}],"wp:attachment":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/media?parent=680586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/categories?post=680586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/tags?post=680586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}