{"id":689556,"date":"2021-11-12T14:22:00","date_gmt":"2021-11-12T06:22:00","guid":{"rendered":"https:\/\/www.cool-style.com.tw\/wd2\/?p=689556"},"modified":"2021-11-12T14:22:02","modified_gmt":"2021-11-12T06:22:02","slug":"%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89","status":"publish","type":"post","link":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89","title":{"rendered":"\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01 BMW \u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1"},"content":{"rendered":"\n<p>BMW \u96c6\u5718\u57f7\u884c\u9577\u9f4a\u666e\u65af\uff08Oliver Zipse\uff09\u4eca\u5e74\u521d\u624d\u5728 DLD All Stars \u5275\u65b0\u5927\u6703\u4e0a\u7a31\uff0c\u7279\u65af\u62c9\uff08Tesla\uff09\u5728\u96fb\u52d5\u8eca\u754c\u7684\u9818\u5c0e\u5730\u4f4d\u5f88\u5feb\u5c31\u6703\u88ab\u50b3\u7d71\u8eca\u5ee0\u53d6\u4ee3\u3002\u8fd1\u65e5\u9f4a\u666e\u65af\u518d\u6b21\u91dd\u5c0d\u7279\u65af\u62c9\uff0c\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\u3002<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/163480199847658_P14376996.jpg\" alt=\"\" class=\"wp-image-689592\" width=\"800\"\/><figcaption>BMW \u8fd1\u5e74\u4f86\u7a4d\u6975\u958b\u767c\u96fb\u52d5\u8eca\u3002\uff08\u5716\u53d6\u81ea BMW\uff09<\/figcaption><\/figure><\/div>\n\n\n\n<p>\u9f4a\u666e\u65af\u5728\u5546\u696d\u5831\u7d19 Handelsblatt \u65bc\u9031\u4e09\u8209\u884c\u7684\u6703\u8b70\u4e0a\u63d0\u53ca\u7279\u65af\u62c9\uff0c\u4ed6\u5f37\u8abf BMW \u548c Tesla \u4e0d\u540c\u4e4b\u8655\u5728\u65bc\u300c\u54c1\u8cea\u548c\u53ef\u9760\u5ea6\u7684\u6a19\u6e96\u300d\uff0c\u66f4\u7a31\u300c\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1\u300d\uff0c\u4f3c\u4e4e\u662f\u5728\u6697\u8af7\u7279\u65af\u62c9\u7684\u8eca\u6b3e\u54c1\u8cea\u4e0d\u4f73\u3002\u6b64\u5916\uff0c\u9f4a\u666e\u65af\u9084\u5c0d\u7279\u65af\u62c9\u7684\u92b7\u552e\u7b56\u7565\u55e4\u4e4b\u4ee5\u9f3b\uff0c\u300c\u4ed6\u5011\uff08\u7279\u65af\u62c9\uff09\u900f\u904e\u964d\u50f9\u4f86\u63d0\u5347\u696d\u7e3e\u6210\u9577\uff0c\u4f46\u6211\u5011\u4e0d\u6703\u9019\u9ebc\u505a\uff0c\u56e0\u70ba\u6211\u5011\u5805\u6301\u9577\u4e45\u7d93\u71df\u3002\u300d<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/pciIX7n2BeMNynt.jpg\" alt=\"\" class=\"wp-image-689594\"\/><figcaption>\u7279\u65af\u62c9\u662f\u5168\u7403\u96fb\u52d5\u8eca\u9f8d\u982d\u3002\uff08\u5716\u53d6\u81ea Tesla\uff09<\/figcaption><\/figure><\/div>\n\n\n\n<p>\u4e0d\u904e\uff0c\u7279\u65af\u62c9\u7684\u7d44\u88dd\u54c1\u8cea\u78ba\u5be6\u4e00\u76f4\u4ee5\u4f86\u90fd\u70ba\u4eba\u8a6c\u75c5\uff0c\u77e5\u540d\u5e02\u8abf\u6a5f\u69cb J.D Power 2021 \u5e74\u7684\u65b0\u8eca\u54c1\u8cea\u8abf\u67e5\u5831\u544a\uff08Initial Quality Study\uff0c\u7c21\u7a31 IQS\uff09\u51fa\u7210\uff0c\u53bb\u5e74\u540a\u8eca\u5c3e\u7684\u7279\u65af\u62c9\uff0c\u4ecd\u4ee5\u6bcf\u4e00\u767e\u8f1b\u8eca\u51fa\u73fe 231 \u500b\u554f\u984c\u7a69\u5750\u5f8c\u6bb5\u73ed\u3002\u5e38\u898b\u7684\u554f\u984c\u4e0d\u4e4f\u70e4\u6f06\u7455\u75b5\u3001\u5167\u88dd\u5bc6\u5408\u5ea6\u3001\u5927\u71c8\u6c34\u6c23\u3001\u8eca\u5167\u6f0f\u6c34\uff0c\u751a\u81f3\u6709\u8eca\u4e3b\u78b0\u4e0a\u5168\u666f\u73bb\u7483\u8eca\u9802\u812b\u843d\u98db\u51fa\u53bb\u3002<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/e5875789.jpg\" alt=\"\" class=\"wp-image-689589\" width=\"800\"\/><figcaption>\u7279\u65af\u62c9\u7684\u54c1\u8cea\u4e00\u76f4\u70ba\u4eba\u8a6c\u75c5\u3002\uff08\u5716\u53d6\u81ea J.D Power\uff09<\/figcaption><\/figure><\/div>\n\n\n\n<p>\u96d6\u7136\u5148\u524d\u5e02\u8abf\u6a5f\u69cb LMC Automotive \u9810\u6e2c\u5831\u544a\u6307\u51fa\uff0c2025 \u5e74\u7279\u65af\u62c9\u7684\u96fb\u52d5\u8eca\u9f8d\u982d\u5bf6\u5ea7\uff0c\u5c07\u88ab\u76ee\u524d\u5168\u7403\u6700\u5927\u7684\u6c7d\u8eca\u96c6\u5718\u798f\u65af\u53d6\u4ee3\uff0c\u7136\u800c\u6578\u64da\u6703\u8aaa\u8a71\uff0c BMW 2021 \u5e74\u524d 9 \u6708\u7e3d\u5171\u552e\u51fa 23 \u842c 1575 \u53f0\u7d14\u96fb\u52d5\u548c\u63d2\u96fb\u5f0f\u6df7\u5408\u52d5\u529b\u8eca\u6b3e\uff0c\u92b7\u552e\u91cf\u6210\u9577 98.8%\uff0c\u4f46\u7279\u65af\u62c9\u5149\u662f 2021 \u5e74\u7b2c\u4e09\u5b63\u5c31\u5df2\u4ea4\u4ed8 24 \u842c 1300 \u53f0\u8eca\u3002\u7531\u6b64\u53ef\u898b\u7279\u65af\u62c9\u7684\u5e02\u5834\u5c1a\u7121\u660e\u986f\u4e0b\u6ed1\u7684\u8de1\u8c61\u3002<\/p>\n\n<div id=\"ad_article_1\" class=\"cool_adgeek_img ad_728x90\" style=\"margin: 10px; text-align: center;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>BMW \u96c6\u5718\u57f7\u884c\u9577\u9f4a\u666e\u65af\uff08Oliver Zipse\uff09\u4eca\u5e74\u521d\u624d\u5728 DLD All Stars \u5275\u65b0\u5927\u6703\u4e0a\u7a31\uff0c\u7279\u65af [&hellip;]<\/p>\n","protected":false},"author":99,"featured_media":689601,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[38456,38458],"tags":[1136,32935],"class_list":["post-689556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-38456","category-38458","tag-bmw","tag-32935"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01 BMW \u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01-bmw-\u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01 BMW \u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2\" \/>\n<meta property=\"og:description\" content=\"BMW \u96c6\u5718\u57f7\u884c\u9577\u9f4a\u666e\u65af\uff08Oliver Zipse\uff09\u4eca\u5e74\u521d\u624d\u5728 DLD All Stars \u5275\u65b0\u5927\u6703\u4e0a\u7a31\uff0c\u7279\u65af [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01-bmw-\u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\" \/>\n<meta property=\"og:site_name\" content=\"COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cool.streetfashion\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T06:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-12T06:22:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/cover041.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Berlin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Berlin\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01 BMW \u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01-bmw-\u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9","og_locale":"zh_TW","og_type":"article","og_title":"\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01 BMW \u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","og_description":"BMW \u96c6\u5718\u57f7\u884c\u9577\u9f4a\u666e\u65af\uff08Oliver Zipse\uff09\u4eca\u5e74\u521d\u624d\u5728 DLD All Stars \u5275\u65b0\u5927\u6703\u4e0a\u7a31\uff0c\u7279\u65af [&hellip;]","og_url":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01-bmw-\u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9","og_site_name":"COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","article_publisher":"https:\/\/www.facebook.com\/cool.streetfashion\/","article_published_time":"2021-11-12T06:22:00+00:00","article_modified_time":"2021-11-12T06:22:02+00:00","og_image":[{"url":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/cover041.jpg","width":1200,"height":628,"type":"image\/jpeg"}],"author":"Berlin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Berlin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89","url":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89","name":"\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01 BMW \u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1 - COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","isPartOf":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89#primaryimage"},"image":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89#primaryimage"},"thumbnailUrl":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/cover041.jpg","datePublished":"2021-11-12T06:22:00+00:00","dateModified":"2021-11-12T06:22:02+00:00","author":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/#\/schema\/person\/ba1d31d0d73271d610e443e4d319861e"},"breadcrumb":{"@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89"]}]},{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89#primaryimage","url":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/cover041.jpg","contentUrl":"https:\/\/cdn-origin.cool-style.com.tw\/cool\/2021\/11\/cover041.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/689556-%e6%9a%97%e8%ab%b7%e7%89%b9%e6%96%af%e6%8b%89%e5%93%81%e7%ae%a1%e4%b8%8d%e4%bd%b3%ef%bc%81-bmw-%e5%9f%b7%e8%a1%8c%e9%95%b7%e9%bd%8a%e6%99%ae%e6%96%af%e7%a8%b1%ef%bc%9a%e7%89%b9%e6%96%af%e6%8b%89#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.cool-style.com.tw\/wd2\/"},{"@type":"ListItem","position":2,"name":"\u6c7d\u6a5f\u8eca","item":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/category\/%e6%b1%bd%e6%a9%9f%e8%bb%8a-2"},{"@type":"ListItem","position":3,"name":"\u6c7d\u8eca","item":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/category\/%e6%b1%bd%e6%a9%9f%e8%bb%8a-2\/%e6%b1%bd%e8%bb%8a"},{"@type":"ListItem","position":4,"name":"\u6697\u8af7\u7279\u65af\u62c9\u54c1\u7ba1\u4e0d\u4f73\uff01 BMW \u57f7\u884c\u9577\u9f4a\u666e\u65af\u7a31\uff1a\u7279\u65af\u62c9\u4e0d\u662f\u9ad8\u7aef\u5e02\u5834\u7684\u4e00\u54e1"}]},{"@type":"WebSite","@id":"https:\/\/www.cool-style.com.tw\/wd2\/#website","url":"https:\/\/www.cool-style.com.tw\/wd2\/","name":"COOL-STYLE \u6f6e\u6d41\u751f\u6d3b\u7db2","description":"\u83ef\u6587\u6f6e\u6d41\u7b2c\u4e00\u54c1\u724c","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cool-style.com.tw\/wd2\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-TW"},{"@type":"Person","@id":"https:\/\/www.cool-style.com.tw\/wd2\/#\/schema\/person\/ba1d31d0d73271d610e443e4d319861e","name":"Berlin","image":{"@type":"ImageObject","inLanguage":"zh-TW","@id":"https:\/\/www.cool-style.com.tw\/wd2\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9a29fc3dbc4225ef10e4c3ac0377807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9a29fc3dbc4225ef10e4c3ac0377807?s=96&d=mm&r=g","caption":"Berlin"},"url":"https:\/\/www.cool-style.com.tw\/wd2\/archives\/author\/min"}]}},"_links":{"self":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts\/689556"}],"collection":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/comments?post=689556"}],"version-history":[{"count":6,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts\/689556\/revisions"}],"predecessor-version":[{"id":689605,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/posts\/689556\/revisions\/689605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/media\/689601"}],"wp:attachment":[{"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/media?parent=689556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/categories?post=689556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cool-style.com.tw\/wd2\/wp-json\/wp\/v2\/tags?post=689556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}